{"id":67723,"date":"2026-02-04T09:59:02","date_gmt":"2026-02-04T14:59:02","guid":{"rendered":"https:\/\/baeagencyusa.com\/?post_type=models-events&#038;p=67723"},"modified":"2026-02-04T09:59:02","modified_gmt":"2026-02-04T14:59:02","slug":"models-67723","status":"publish","type":"models-events","link":"https:\/\/baeagencyusa.com\/pt\/models-events\/models-67723\/","title":{"rendered":"Models #67723"},"featured_media":0,"parent":0,"template":"","_states":[],"_countries":[],"dress-size":[],"_shoes":[],"_hips":[],"_waist":[],"_bust":[],"_hair":[787],"_height":[767],"_eyes":[],"_nationality":[],"_ethnicity":[],"class_list":["post-67723","models-events","type-models-events","status-publish","hentry","_hair-black","_height-767"],"complete_data":{"name":"Noelani","age":"49","nationality":"American","country":"United States","languages":"","height":"5' 6\" \/ 167 CM","thumb_url":"https:\/\/baeagencyusa.com\/wp-content\/uploads\/jet-form-builder\/95b458296cfa71477a692eea9fee2c3a\/cropped-image.png","ugc_video_1_url":false,"ugc_video_2_url":false,"gallery":["https:\/\/baeagencyusa.com\/wp-content\/uploads\/jet-form-builder\/0f47de30ed9561664baba4ed633b134b\/IMG_3757.jpeg","https:\/\/baeagencyusa.com\/wp-content\/uploads\/jet-form-builder\/0f47de30ed9561664baba4ed633b134b\/IMG_9700-scaled.jpeg","https:\/\/baeagencyusa.com\/wp-content\/uploads\/jet-form-builder\/0f47de30ed9561664baba4ed633b134b\/IMG_3266-scaled.jpeg"]},"_links":{"self":[{"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/models-events\/67723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/models-events"}],"about":[{"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/types\/models-events"}],"wp:attachment":[{"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/media?parent=67723"}],"wp:term":[{"taxonomy":"_states","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_states?post=67723"},{"taxonomy":"_countries","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_countries?post=67723"},{"taxonomy":"dress-size","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/dress-size?post=67723"},{"taxonomy":"_shoes","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_shoes?post=67723"},{"taxonomy":"_hips","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_hips?post=67723"},{"taxonomy":"_waist","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_waist?post=67723"},{"taxonomy":"_bust","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_bust?post=67723"},{"taxonomy":"_hair","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_hair?post=67723"},{"taxonomy":"_height","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_height?post=67723"},{"taxonomy":"_eyes","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_eyes?post=67723"},{"taxonomy":"_nationality","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_nationality?post=67723"},{"taxonomy":"_ethnicity","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_ethnicity?post=67723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}