{"id":66359,"date":"2026-01-13T16:34:03","date_gmt":"2026-01-13T21:34:03","guid":{"rendered":"https:\/\/baeagencyusa.com\/?post_type=models-events&#038;p=66359"},"modified":"2026-01-13T16:34:03","modified_gmt":"2026-01-13T21:34:03","slug":"models-66359","status":"publish","type":"models-events","link":"https:\/\/baeagencyusa.com\/pt\/models-events\/models-66359\/","title":{"rendered":"Models #66359"},"featured_media":0,"parent":0,"template":"","_states":[],"_countries":[],"dress-size":[],"_shoes":[],"_hips":[],"_waist":[],"_bust":[],"_hair":[787],"_height":[767],"_eyes":[],"_nationality":[],"_ethnicity":[],"class_list":["post-66359","models-events","type-models-events","status-publish","hentry","_hair-black","_height-767"],"complete_data":{"name":"andypromo2018","age":"29","nationality":"Haitian","country":"United States","languages":"","height":"5' 6\" \/ 167 CM","thumb_url":false,"ugc_video_1_url":false,"ugc_video_2_url":false,"gallery":["https:\/\/baeagencyusa.com\/wp-content\/uploads\/jet-form-builder\/de6aa642124d02fd2b314acd7f1ab943\/IMG_0105-scaled.jpeg","https:\/\/baeagencyusa.com\/wp-content\/uploads\/jet-form-builder\/de6aa642124d02fd2b314acd7f1ab943\/E68B8108-F14B-4F2B-A361-5E415AE08850-scaled.jpeg","https:\/\/baeagencyusa.com\/wp-content\/uploads\/jet-form-builder\/de6aa642124d02fd2b314acd7f1ab943\/d9713b40-7a41-4d23-8f90-bebc38939f35-scaled.jpeg"]},"_links":{"self":[{"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/models-events\/66359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/models-events"}],"about":[{"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/types\/models-events"}],"wp:attachment":[{"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/media?parent=66359"}],"wp:term":[{"taxonomy":"_states","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_states?post=66359"},{"taxonomy":"_countries","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_countries?post=66359"},{"taxonomy":"dress-size","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/dress-size?post=66359"},{"taxonomy":"_shoes","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_shoes?post=66359"},{"taxonomy":"_hips","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_hips?post=66359"},{"taxonomy":"_waist","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_waist?post=66359"},{"taxonomy":"_bust","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_bust?post=66359"},{"taxonomy":"_hair","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_hair?post=66359"},{"taxonomy":"_height","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_height?post=66359"},{"taxonomy":"_eyes","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_eyes?post=66359"},{"taxonomy":"_nationality","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_nationality?post=66359"},{"taxonomy":"_ethnicity","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_ethnicity?post=66359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}