{"id":60713,"date":"2025-10-09T15:20:46","date_gmt":"2025-10-09T20:20:46","guid":{"rendered":"https:\/\/baeagencyusa.com\/?post_type=models-events&#038;p=60713"},"modified":"2025-10-09T15:20:46","modified_gmt":"2025-10-09T20:20:46","slug":"models-60713","status":"publish","type":"models-events","link":"https:\/\/baeagencyusa.com\/pt\/models-events\/models-60713\/","title":{"rendered":"Models #60713"},"featured_media":0,"parent":0,"template":"","_states":[],"_countries":[],"dress-size":[],"_shoes":[],"_hips":[],"_waist":[],"_bust":[],"_hair":[788],"_height":[767],"_eyes":[],"_nationality":[],"_ethnicity":[],"class_list":["post-60713","models-events","type-models-events","status-publish","hentry","_hair-blonde","_height-767"],"complete_data":{"name":"Isabela Moretti","age":"26","nationality":"Brazilian","country":"Brazil","languages":"","height":"5' 6\" \/ 167 CM","thumb_url":"https:\/\/baeagencyusa.com\/wp-content\/uploads\/jet-form-builder\/36e746ee9041e03783c5b1d865b010f6\/D8BF0E03-8231-494C-B29D-1036FF91B5DF-scaled.jpeg","ugc_video_1_url":false,"ugc_video_2_url":false,"gallery":["https:\/\/baeagencyusa.com\/wp-content\/uploads\/jet-form-builder\/130b98e4d3f7bdcf890e90ca3c3ab43f\/1EDC8008-542A-4239-A576-7038D39F119D-scaled.jpeg","https:\/\/baeagencyusa.com\/wp-content\/uploads\/jet-form-builder\/130b98e4d3f7bdcf890e90ca3c3ab43f\/IMG_7788-1-scaled.jpeg","https:\/\/baeagencyusa.com\/wp-content\/uploads\/jet-form-builder\/130b98e4d3f7bdcf890e90ca3c3ab43f\/IMG_7784-scaled.jpeg"]},"_links":{"self":[{"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/models-events\/60713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/models-events"}],"about":[{"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/types\/models-events"}],"wp:attachment":[{"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/media?parent=60713"}],"wp:term":[{"taxonomy":"_states","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_states?post=60713"},{"taxonomy":"_countries","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_countries?post=60713"},{"taxonomy":"dress-size","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/dress-size?post=60713"},{"taxonomy":"_shoes","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_shoes?post=60713"},{"taxonomy":"_hips","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_hips?post=60713"},{"taxonomy":"_waist","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_waist?post=60713"},{"taxonomy":"_bust","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_bust?post=60713"},{"taxonomy":"_hair","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_hair?post=60713"},{"taxonomy":"_height","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_height?post=60713"},{"taxonomy":"_eyes","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_eyes?post=60713"},{"taxonomy":"_nationality","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_nationality?post=60713"},{"taxonomy":"_ethnicity","embeddable":true,"href":"https:\/\/baeagencyusa.com\/pt\/wp-json\/wp\/v2\/_ethnicity?post=60713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}